{"id":1995437,"date":"2020-11-18T15:14:08","date_gmt":"2020-11-18T14:14:08","guid":{"rendered":"https:\/\/de.tilta.com\/shop\/rosette-extender-arm\/"},"modified":"2026-04-23T13:44:16","modified_gmt":"2026-04-23T11:44:16","slug":"rosette-extender-arm","status":"publish","type":"product","link":"https:\/\/eu.tilta.com\/it\/shop\/rosette-extender-arm\/","title":{"rendered":"Braccio estensore del rosone"},"content":{"rendered":"<p>Questo braccio estensore ti permette di regolare l&#8217;angolo e la lunghezza delle maniglie operative per ottenere il massimo comfort di utilizzo.<\/p>\n<p>\u00c8 dotato di connessioni per rosette standard Arri, quindi pu\u00f2 essere collegato a qualsiasi rosetta compatibile.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questo braccio estensore ti permette di regolare l&#8217;angolo e la lunghezza delle maniglie operative per ottenere il massimo comfort di utilizzo. \u00c8 dotato di connessioni per rosette standard Arri, quindi pu\u00f2 essere collegato a qualsiasi rosetta compatibile.<\/p>\n","protected":false},"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[2250,2164],"product_tag":[],"acf":[],"gallery_images":[1065952,1065953,994315],"_links":{"self":[{"href":"https:\/\/eu.tilta.com\/it\/wp-json\/wp\/v2\/product\/1995437"}],"collection":[{"href":"https:\/\/eu.tilta.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/eu.tilta.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/eu.tilta.com\/it\/wp-json\/wp\/v2\/comments?post=1995437"}],"wp:attachment":[{"href":"https:\/\/eu.tilta.com\/it\/wp-json\/wp\/v2\/media?parent=1995437"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/eu.tilta.com\/it\/wp-json\/wp\/v2\/product_cat?post=1995437"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/eu.tilta.com\/it\/wp-json\/wp\/v2\/product_tag?post=1995437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}